{"id":5770,"date":"2019-01-24T02:58:26","date_gmt":"2019-01-24T06:58:26","guid":{"rendered":"https:\/\/avech.org\/?p=5770"},"modified":"2022-10-13T03:01:40","modified_gmt":"2022-10-13T07:01:40","slug":"china-rechaza-injerencia-en-venezuela-y-apoya-su-soberania","status":"publish","type":"post","link":"https:\/\/avech.org\/en\/china-rechaza-injerencia-en-venezuela-y-apoya-su-soberania\/","title":{"rendered":"China rechaza injerencia en Venezuela y apoya su soberan\u00eda"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-bottom:80px;--awb-padding-right-medium:60px;--awb-padding-left-medium:60px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1331.2px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:40px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\" style=\"--awb-content-alignment:justify;\"><h1 style=\"text-align: center;\"><strong>China rechaza injerencia en Venezuela y apoya su soberan\u00eda<\/strong><\/h1>\n<p>China expres\u00f3 hoy oposici\u00f3n a la injerencia extranjera en los asuntos de Venezuela, ratific\u00f3 el apoyo al gobierno del presidente Nicol\u00e1s Maduro y a sus esfuerzos por salvaguardar la soberan\u00eda, independencia y estabilidad nacional del pa\u00eds.<\/p>\n<p>Hua Chunying, portavoz del Ministerio de Relaciones Exteriores, dijo en rueda de prensa que Beijing est\u00e1 atento al masivo rechazo a una posible intervenci\u00f3n militar en el pa\u00eds suramericano y aboga porque la situaci\u00f3n all\u00ed se resuelva de forma pac\u00edfica, mediante las negociaciones y de conformidad con la Constituci\u00f3n.<\/p>\n<p>\u2018China espera que todas las partes en Venezuela resuelvan sus diferencias pol\u00edticas a trav\u00e9s del di\u00e1logo y la consulta, eviten los conflictos violentos y restauren el orden normal seg\u00fan los intereses fundamentales del pa\u00eds y del pueblo\u2019, indic\u00f3. Al mismo tiempo, Hua rechaz\u00f3 la interferencia externa en los asuntos venezolanos y dese\u00f3 que la comunidad internacional propicie las condiciones favorables para evitar esa pr\u00e1ctica.<\/p>\n<p>Consider\u00f3 que Estados Unidos y Venezuela son pa\u00edses importantes en el hemisferio occidental y sus relaciones deben regirse sobre la base del trato igualitario y el respeto mutuo.<\/p>\n<p>La vocera de la Canciller\u00eda a\u00f1adi\u00f3 que las sanciones y la intromisi\u00f3n en cuestiones internas son mecanismos que solo \u2018tienden a complicar la situaci\u00f3n y no contribuyen a la resoluci\u00f3n de problemas pr\u00e1cticos.\u2019<\/p>\n<p>Con sus declaraciones China se suma a otros gobiernos que respaldan a Venezuela tras el intento de golpe de estado promovido por Estados Unidos, al reconocer la autoproclamaci\u00f3n inconstitucional de Juan Guaid\u00f3 como mandatario interino.<\/p>\n<p>Maduro anunci\u00f3 la ruptura de las relaciones diplom\u00e1ticas con el pa\u00eds norteamericano a ra\u00edz de ese hecho.<\/p>\n<p>El Dignatario comenz\u00f3 su segundo mandato el 10 de enero luego de resultar reelecto en mayo pasado con 67 por ciento de los votos v\u00e1lidos emitidos en los comicios presidenciales.<\/p>\n<p>Esas elecciones la avalaron organismos internacionales por su desarrollo apegado a las leyes y el respeto a las garant\u00edas de todos los partidos, candidatos y votantes.<\/p>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:5px;width:100%;\"><\/div><div class=\"fusion-text fusion-text-2\"><p style=\"text-align: justify;\"><strong>Fuente:<\/strong> Ministerio del Poder Popular para Relaciones Exteriores de Venezuela.<\/p>\n<p><a href=\"http:\/\/mppre.gob.ve\/2019\/01\/24\/china-rechaza-injerencia-en-venezuela-apoya-soberania\/\" target=\"_blank\" rel=\"noopener\">http:\/\/mppre.gob.ve\/2019\/01\/24\/china-rechaza-injerencia-en-venezuela-apoya-soberania\/<\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":5366,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49,48],"tags":[47,198,86],"class_list":["post-5770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-observatorio","category-observatorio","tag-china","tag-relaciones-diplomaticas","tag-venezuela"],"_links":{"self":[{"href":"https:\/\/avech.org\/en\/wp-json\/wp\/v2\/posts\/5770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avech.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/avech.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/avech.org\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/avech.org\/en\/wp-json\/wp\/v2\/comments?post=5770"}],"version-history":[{"count":1,"href":"https:\/\/avech.org\/en\/wp-json\/wp\/v2\/posts\/5770\/revisions"}],"predecessor-version":[{"id":5771,"href":"https:\/\/avech.org\/en\/wp-json\/wp\/v2\/posts\/5770\/revisions\/5771"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/avech.org\/en\/wp-json\/wp\/v2\/media\/5366"}],"wp:attachment":[{"href":"https:\/\/avech.org\/en\/wp-json\/wp\/v2\/media?parent=5770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/avech.org\/en\/wp-json\/wp\/v2\/categories?post=5770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/avech.org\/en\/wp-json\/wp\/v2\/tags?post=5770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}